{"id":41409,"date":"2013-09-12T00:36:18","date_gmt":"2013-09-12T07:36:18","guid":{"rendered":"https:\/\/soccercampsinternational.com\/fotos-de-los-campos-de-futbol-del-paris-saint-germain\/"},"modified":"2026-04-15T18:39:30","modified_gmt":"2026-04-16T01:39:30","slug":"fotos","status":"publish","type":"page","link":"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/fotos\/","title":{"rendered":"Fotos Campamentos de f\u00fatbol Paris Saint Germain"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"41409\" class=\"elementor elementor-41409 elementor-1450\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97543d0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97543d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4eae125\" data-id=\"4eae125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-168fbf9 elementor-widget-tablet__width-auto elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"168fbf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-168fbf9\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-42071\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/\" class=\"elementor-item\">PSG Campamentos \/ Precios \/ Fechas<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42072\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/sitios-detalles\/\" class=\"elementor-sub-item\">Ubicaci\u00f3n y Detalles<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42070\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/informacion-traslado-aeropuerto\/\" class=\"elementor-sub-item\">Traslados Aeropuerto y Preguntas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42069\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/fotos\/\" class=\"elementor-sub-item\">Fotos<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-168fbf9\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-42071\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/\" class=\"elementor-item\" tabindex=\"-1\">PSG Campamentos \/ Precios \/ Fechas<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42072\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/sitios-detalles\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ubicaci\u00f3n y Detalles<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42070\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/informacion-traslado-aeropuerto\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Traslados Aeropuerto y Preguntas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-42069\"><a href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/fotos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fotos<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5a56e3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5a56e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65843d8\" data-id=\"65843d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31289d6 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"31289d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-images\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480 416v16c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48V176c0-26.51 21.49-48 48-48h16v48H54a6 6 0 0 0-6 6v244a6 6 0 0 0 6 6h372a6 6 0 0 0 6-6v-10h48zm42-336H150a6 6 0 0 0-6 6v244a6 6 0 0 0 6 6h372a6 6 0 0 0 6-6V86a6 6 0 0 0-6-6zm6-48c26.51 0 48 21.49 48 48v256c0 26.51-21.49 48-48 48H144c-26.51 0-48-21.49-48-48V80c0-26.51 21.49-48 48-48h384zM264 144c0 22.091-17.909 40-40 40s-40-17.909-40-40 17.909-40 40-40 40 17.909 40 40zm-72 96l39.515-39.515c4.686-4.686 12.284-4.686 16.971 0L288 240l103.515-103.515c4.686-4.686 12.284-4.686 16.971 0L480 208v80H192v-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fotos del campamento de la Academia del Par\u00eds Saint Germain<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b239efc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b239efc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-484b279\" data-id=\"484b279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2f6fc5 elementor-widget elementor-widget-gallery\" data-id=\"d2f6fc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns_mobile&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-1-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyNTIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTEtMTAuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-1-10.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo11.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MTgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1waG90bzExLmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo11.jpg\" data-width=\"1024\" data-height=\"768\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MTIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1waG90bzMuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo3.jpg\" data-width=\"1024\" data-height=\"576\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MDYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1waG90bzIuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-photo2.jpg\" data-width=\"660\" data-height=\"335\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-15.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MDAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-15.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-14.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1OTQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMTQuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-14.jpg\" data-width=\"1400\" data-height=\"788\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-12.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1ODgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMTIuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-12.jpg\" data-width=\"1400\" data-height=\"788\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-11.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1ODIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMTEuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-11.jpg\" data-width=\"1400\" data-height=\"788\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NzYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMTAuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-10.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NzAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtOS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-9.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NjQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtOC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-8.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NTgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtNi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-6.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NTIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtNS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-5.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NDYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtNC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-4.jpg\" data-width=\"2048\" data-height=\"1152\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NDAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMy5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-3.jpg\" data-width=\"2048\" data-height=\"1152\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MzQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-2.jpg\" data-width=\"2048\" data-height=\"1152\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MjgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUGFyaXMtU2FpbnQtR2VybWFpbi1BY2FkZW15LUNhbXAtMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/Paris-Saint-Germain-Academy-Camp-1.jpg\" data-width=\"960\" data-height=\"538\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img28-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MjIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjgtMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img28-1.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img27-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MTYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjctMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img27-1.jpg\" data-width=\"960\" data-height=\"540\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img26-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MTAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjYtMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img26-1.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img25-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MDQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjUtMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img25-1.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img24-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0OTgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjQtMS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img24-1.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img23-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0OTIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjMtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img23-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img22-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0ODYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjItMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img22-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img21-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0ODAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjEtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img21-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img20-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NzQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMjAtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img20-2.jpg\" data-width=\"960\" data-height=\"538\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img16-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NjgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTYtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img16-2.jpg\" data-width=\"960\" data-height=\"538\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img15-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NjIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTUtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img15-2.jpg\" data-width=\"960\" data-height=\"538\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img14-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NTYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTQtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img14-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img13-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NTAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTMtMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img13-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img12-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NDQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTItMi5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img12-2.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img11-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MzgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTEtMy5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img11-3.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img10-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MzIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMTAtMy5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img10-3.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img9-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MjYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nOS00LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img9-4.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img8-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MjAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nOC00LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img8-4.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img7-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MTQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nNy02LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img7-6.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img6-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MDgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nNi02LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img6-6.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img5-7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0MDIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nNS03LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img5-7.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img3-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzOTYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMy04LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img3-8.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img2-7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzOTAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMi03LmpwZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img2-7.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img1-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzODQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nMS0xMC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img1-10.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-31-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNzgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTMxLTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-31-5.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-30-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNzIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTMwLTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-30-5.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-29-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNjYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI5LTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-29-5.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-28-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNjAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI4LTQuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-28-4.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-27-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNTQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI3LTQuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-27-4.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-26-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNDgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI2LTQuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-26-4.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-25-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzNDIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI1LTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-25-5.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-24-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMzYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTI0LTUuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-24-5.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-23-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMzAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTIzLTYuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-23-6.jpg\" data-width=\"960\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-16-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMjQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTE2LTYuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-16-6.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-15-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMTgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTE1LTYuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-15-6.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-11-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMTIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTExLTYuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-11-6.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-10-7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMDYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTEwLTcuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-10-7.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-9-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkzMDAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTktOC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-9-8.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-8-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyOTQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTgtOC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-8-8.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-field-2-synt.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MjQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUFNHLWZpZWxkLTItc3ludC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-field-2-synt.jpg\" data-width=\"1024\" data-height=\"768\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/psg-field.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MzAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvcHNnLWZpZWxkLnBuZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/psg-field.png\" data-width=\"1024\" data-height=\"475\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-indoor.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2MzYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUFNHLWluZG9vci5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-indoor.jpg\" data-width=\"1024\" data-height=\"683\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-room.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk2NDIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvUFNHLXJvb20uanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/PSG-room.jpg\" data-width=\"1024\" data-height=\"683\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-7-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyODgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTctOS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-7-9.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-6-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyODIsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTYtOS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-6-9.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-5-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyNzYsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTUtOS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-5-9.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-4-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyNzAsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTQtMTAuanBnIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-4-10.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-3-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyNjQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTMtOS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-3-9.jpg\" data-width=\"720\" data-height=\"960\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-2-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Campamento de la Academia del Par\u00eds Saint-Germain\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyNTgsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wOVwvaW1nLTItOC5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/09\/img-2-8.jpg\" data-width=\"960\" data-height=\"720\" aria-label=\"Campamento de la Academia del Par\u00eds Saint-Germain\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/12\/food.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"alimentos\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE1NDcsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMlwvZm9vZC53ZWJwIiwic2xpZGVzaG93IjoiZDJmNmZjNSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/12\/food.webp\" data-width=\"1920\" data-height=\"1440\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/11\/PSG-academy-Athletica.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"Academia de f\u00fatbol del PSG Athletica Paris\" data-elementor-lightbox-description=\"Paris Saint Germain Academia de f\u00fatbol Campamentos Athletica Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEzOTcsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMVwvUFNHLWFjYWRlbXktQXRobGV0aWNhLnBuZyIsInNsaWRlc2hvdyI6ImQyZjZmYzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/11\/PSG-academy-Athletica.png\" data-width=\"768\" data-height=\"400\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/12\/terrainAthletica.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d2f6fc5\" data-elementor-lightbox-title=\"terrenoAthletica\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE1NTQsInVybCI6Imh0dHBzOlwvXC9zb2NjZXJjYW1wc2ludGVybmF0aW9uYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMlwvdGVycmFpbkF0aGxldGljYS5qcGciLCJzbGlkZXNob3ciOiJkMmY2ZmM1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/soccercampsinternational.com\/wp-content\/uploads\/2024\/12\/terrainAthletica.jpg\" data-width=\"768\" data-height=\"511\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e207fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6e207fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/soccercampsinternational.com\/es\/campamentos-futbol-francia\/campamentos-psg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" icomoon-the7-font-the7-home-022\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INICIO DEL CAMPAMENTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fotos del campamento de la Academia del Par\u00eds Saint Germain INICIO DEL CAMPAMENTO<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":41412,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mo_disable_npp":"","footnotes":""},"class_list":["post-41409","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/pages\/41409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/comments?post=41409"}],"version-history":[{"count":0,"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/pages\/41409\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/pages\/41412"}],"wp:attachment":[{"href":"https:\/\/soccercampsinternational.com\/es\/wp-json\/wp\/v2\/media?parent=41409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}